{"id":2334,"date":"2026-02-11T13:58:13","date_gmt":"2026-02-11T11:58:13","guid":{"rendered":"https:\/\/holyseeembassy.orderofmalta.int\/?post_type=news&#038;p=2334"},"modified":"2026-02-13T14:06:24","modified_gmt":"2026-02-13T12:06:24","slug":"premio-inclusione-impegno-cuore","status":"publish","type":"news","link":"https:\/\/holyseeembassy.orderofmalta.int\/it\/notizie\/premio-inclusione-impegno-cuore\/","title":{"rendered":"Un premio che parla di inclusione, impegno e cuore"},"featured_media":0,"menu_order":0,"template":"","class_list":["post-2334","news","type-news","status-publish","hentry","news_categories-notizie"],"acf":{"hidden_news":"no","evidence":"yes","focus_on":"no","breaking":"yes","news_cover":{"id":2335,"url":"https:\/\/holyseeembassy.orderofmalta.int\/wp-content\/uploads\/sites\/3\/2026\/02\/OSTIENSE_103-002-scaled-e1770983991372.jpg"},"cover_image_copyrighted":false,"news_content":"<div class=\"x_elementToProof\" data-olk-copy-source=\"MessageBody\">Gli alloggi del Progetto GIOIA, in Via Ostiense 103 (<a title=\"https:\/\/linkprotect.cudasvc.com\/url?a=https%3a%2f%2fwww.progettogioia.com&amp;c=E,1,lR52_b0FbCXWM991v1yRpTOBt3T4MNIV_cf4WuGzNCx3ZJG0jifyBxdRHx3S_JN5G4L1bgdK3XhojMl9YJMSMaC-tMccy9gvbOW25oRXuGYCwCkEGl20A0EEyg,,&amp;typo=1&amp;ancr_add=1\" href=\"https:\/\/linkprotect.cudasvc.com\/url?a=https%3a%2f%2fwww.progettogioia.com&amp;c=E,1,lR52_b0FbCXWM991v1yRpTOBt3T4MNIV_cf4WuGzNCx3ZJG0jifyBxdRHx3S_JN5G4L1bgdK3XhojMl9YJMSMaC-tMccy9gvbOW25oRXuGYCwCkEGl20A0EEyg,,&amp;typo=1&amp;ancr_add=1\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">www.progettogioia.com<\/a>) hanno ricevuto dalla piattaforma\u00a0<a title=\"https:\/\/linkprotect.cudasvc.com\/url?a=https%3a%2f%2fBooking.com&amp;c=E,1,Jo0UorYQv66OFq1KV6oRuu9foAJVR7npeU6Xh9lS1lVlV-6wNV4dyWXWMQH_nqM-wiqFwQiHqIR6ZnkG8eBVt6JGaSLAIke57tHeZNOP6ZpPeh8ok5TthA,,&amp;typo=1&amp;ancr_add=1\" href=\"https:\/\/linkprotect.cudasvc.com\/url?a=https%3a%2f%2fBooking.com&amp;c=E,1,Jo0UorYQv66OFq1KV6oRuu9foAJVR7npeU6Xh9lS1lVlV-6wNV4dyWXWMQH_nqM-wiqFwQiHqIR6ZnkG8eBVt6JGaSLAIke57tHeZNOP6ZpPeh8ok5TthA,,&amp;typo=1&amp;ancr_add=1\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"1\">Booking.com<\/a>\u00a0il premio &#8220;Traveller Review Award 2026&#8221;, un riconoscimento che viene assegnato alle strutture pi\u00f9 apprezzate dagli ospiti, basato sulle recensioni reali chi ha vissuto l&#8217;esperienza.<\/div>\n<div class=\"x_elementToProof\">Gli alloggi turistici sono pensati\u00a0per accogliere tutti, con particolare attenzione alle famiglie e ai viaggiatori con esigenze speciali. Spazi senza barriere architettoniche, ambienti curati e accoglienti, e un\u2019atmosfera inclusiva rendono il soggiorno a Roma un\u2019esperienza serena e piacevole.<\/div>\n<div class=\"x_elementToProof\">Il Progetto G.I.O.I.A. si regge esclusivamente grazie alla disponibilit\u00e0 degli appartamenti del Gran Priorato di Roma e al generoso sostegno di alcuni sponsor italiani e nord-americani, che hanno fornito le risorse per i lavori in corso e per l\u2019avvio delle prime attivit\u00e0. La ricerca di finanziamenti \u00e8 tutt\u2019ora in corso per dotare il Progetto di un volano finanziario che ne garantisca la durata nel corso degli anni e ne consenta un\u2019auspicabile crescita nel numero dei giovani disabili assistiti.<\/div>\n<div><\/div>\n<div class=\"x_elementToProof\">Per ulteriori informazioni e\/o per donazioni, si prega di rivolgersi alla Segreteria dell\u2019Ambasciata: &#104;&#x6f;l&#121;&#x73;e&#x65;&#x65;&#109;&#x62;a&#115;&#x73;y&#64;&#x6f;&#114;&#x64;e&#114;&#x6f;f&#109;&#x61;&#108;&#x74;&#x61;&#46;&#x69;n&#116;<\/div>\n<div class=\"x_elementToProof\"><\/div>\n","news_gallery":"no","news_excerpt":"Gli alloggi del Progetto GIOIA, in Via Ostiense 103 (www.progettogioia.com) hanno ricevuto dalla piattaforma\u00a0Booking.com\u00a0il premio \"Traveller Review Award 2026\", un riconoscimento che viene assegnato alle strutture pi\u00f9 apprezzate dagli ospiti, basato sulle recensioni reali chi ha vissuto l'esperienza."},"news_categories":[{"id":17,"name":"Notizie","slug":"notizie","description":"","link":"https:\/\/holyseeembassy.orderofmalta.int\/it\/categorie-notizie\/notizie\/"}],"_links":{"self":[{"href":"https:\/\/holyseeembassy.orderofmalta.int\/it\/wp-json\/wp\/v2\/notizie\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holyseeembassy.orderofmalta.int\/it\/wp-json\/wp\/v2\/notizie"}],"about":[{"href":"https:\/\/holyseeembassy.orderofmalta.int\/it\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":1,"href":"https:\/\/holyseeembassy.orderofmalta.int\/it\/wp-json\/wp\/v2\/notizie\/2334\/revisions"}],"predecessor-version":[{"id":2337,"href":"https:\/\/holyseeembassy.orderofmalta.int\/it\/wp-json\/wp\/v2\/notizie\/2334\/revisions\/2337"}],"wp:attachment":[{"href":"https:\/\/holyseeembassy.orderofmalta.int\/it\/wp-json\/wp\/v2\/media?parent=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}